{"id":4424,"date":"2020-01-22T13:24:45","date_gmt":"2020-01-22T12:24:45","guid":{"rendered":"http:\/\/www.pastisseriespomar.es\/?p=4424"},"modified":"2020-01-22T13:29:35","modified_gmt":"2020-01-22T12:29:35","slug":"estruquinis","status":"publish","type":"post","link":"http:\/\/www.pastisseriespomar.es\/ca\/estruquinis\/","title":{"rendered":"Estruquinis"},"content":{"rendered":"<div class=\"wp-block-image\"><figure class=\"alignleft\"><img loading=\"lazy\" width=\"512\" height=\"512\" src=\"http:\/\/www.pastisseriespomar.es\/wp-content\/uploads\/2020\/01\/oie_22132411QAB0j5Gv.jpg\" alt=\"\" class=\"wp-image-4425\" srcset=\"http:\/\/www.pastisseriespomar.es\/wp-content\/uploads\/2020\/01\/oie_22132411QAB0j5Gv.jpg 512w, http:\/\/www.pastisseriespomar.es\/wp-content\/uploads\/2020\/01\/oie_22132411QAB0j5Gv-150x150.jpg 150w, http:\/\/www.pastisseriespomar.es\/wp-content\/uploads\/2020\/01\/oie_22132411QAB0j5Gv-300x300.jpg 300w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/><\/figure><\/div>\n\n\n\n<p>Si habitualment vos duim receptes per a golafres, avui en duim una per a MOLT golafres!<\/p>\n\n\n\n<p>Vos duim uns \u201cpetits pecats\u201d de merengue dol\u00e7 que es mengen tan i tan b\u00e9, i s\u00f3n tan i tan bons, que s\u00f3n gaireb\u00e9 addictius! (I despr\u00e9s no digueu que no vos hem avisat!)<\/p>\n\n\n\n<p>Si no vos en recordau del nom a l'hora de demanar-ne a les nostres pastisseries de Campos o de Palma (es diuen estruquinis, per\u00f2 ens ho han demanat de mil maneres diferents!), no passeu pena. Bastar\u00e0 que digueu a les nostres dependentes que voleu un d'aquells \u201cnigulets de merengue al forn\u201d, i ben segur que vos entendran!<\/p>\n\n\n\n<p>Els ingredients no poden ser m\u00e9s b\u00e0sics: blanc d'ou, sucre, forn i amor. El resultat \u00e9s me-ra-ve-ll\u00f3s!<\/p>\n\n\n\n<p>Tastau-los!&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>Si habitualmente os traemos recetas para \u201cgolosos\u201d hoy se la dedicamos a los s\u00faper golosos! Os traemos unos \u201cpeque\u00f1os pecados\u201d de merengue dulce que se comen tan y tan f\u00e1cil y est\u00e1n tan y tan ricos (luego no dig\u00e1is que no os avisamos), que son casi adictivos! Y si no os acord\u00e1is del nombre a [&hellip;]<\/p>","protected":false},"author":1,"featured_media":4425,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/posts\/4424"}],"collection":[{"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/comments?post=4424"}],"version-history":[{"count":1,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/posts\/4424\/revisions"}],"predecessor-version":[{"id":4426,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/posts\/4424\/revisions\/4426"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/media\/4425"}],"wp:attachment":[{"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/media?parent=4424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/categories?post=4424"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.pastisseriespomar.es\/ca\/wp-json\/wp\/v2\/tags?post=4424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}